{"id":44,"count":12,"description":"","link":"https:\/\/mazarrononline.com\/en\/category\/restaurantes-frente-al-mar-mazarron\/","name":"Restaurantes Frente al Mar en Mazarr\u00f3n","slug":"restaurantes-frente-al-mar-mazarron","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Restaurantes Frente al Mar en Mazarr\u00f3n archivos - Mazarron Online<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mazarrononline.com\/en\/category\/restaurantes-frente-al-mar-mazarron\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Restaurantes Frente al Mar en Mazarr\u00f3n archivos - Mazarron Online\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mazarrononline.com\/en\/category\/restaurantes-frente-al-mar-mazarron\/\" \/>\n<meta property=\"og:site_name\" content=\"Mazarron Online\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/mazarrononline.com\\\/category\\\/restaurantes-frente-al-mar-mazarron\\\/\",\"url\":\"https:\\\/\\\/mazarrononline.com\\\/category\\\/restaurantes-frente-al-mar-mazarron\\\/\",\"name\":\"Restaurantes Frente al Mar en Mazarr\u00f3n archivos - Mazarron Online\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mazarrononline.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mazarrononline.com\\\/category\\\/restaurantes-frente-al-mar-mazarron\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mazarrononline.com\\\/category\\\/restaurantes-frente-al-mar-mazarron\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/mazarrononline.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Restaurantes Frente al Mar en Mazarr\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mazarrononline.com\\\/#website\",\"url\":\"https:\\\/\\\/mazarrononline.com\\\/\",\"name\":\"Mazarron Online\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mazarrononline.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mazarrononline.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mazarrononline.com\\\/#organization\",\"name\":\"Mazarron Online\",\"url\":\"https:\\\/\\\/mazarrononline.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/mazarrononline.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mazarrononline.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/mazarrononline.com_.png\",\"contentUrl\":\"https:\\\/\\\/mazarrononline.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/mazarrononline.com_.png\",\"width\":891,\"height\":340,\"caption\":\"Mazarron Online\"},\"image\":{\"@id\":\"https:\\\/\\\/mazarrononline.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Restaurantes Frente al Mar en Mazarr\u00f3n archivos - Mazarron Online","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mazarrononline.com\/en\/category\/restaurantes-frente-al-mar-mazarron\/","og_locale":"en_GB","og_type":"article","og_title":"Restaurantes Frente al Mar en Mazarr\u00f3n archivos - Mazarron Online","og_url":"https:\/\/mazarrononline.com\/en\/category\/restaurantes-frente-al-mar-mazarron\/","og_site_name":"Mazarron Online","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/mazarrononline.com\/category\/restaurantes-frente-al-mar-mazarron\/","url":"https:\/\/mazarrononline.com\/category\/restaurantes-frente-al-mar-mazarron\/","name":"Restaurantes Frente al Mar en Mazarr\u00f3n archivos - Mazarron Online","isPartOf":{"@id":"https:\/\/mazarrononline.com\/#website"},"breadcrumb":{"@id":"https:\/\/mazarrononline.com\/category\/restaurantes-frente-al-mar-mazarron\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/mazarrononline.com\/category\/restaurantes-frente-al-mar-mazarron\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mazarrononline.com\/"},{"@type":"ListItem","position":2,"name":"Restaurantes Frente al Mar en Mazarr\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/mazarrononline.com\/#website","url":"https:\/\/mazarrononline.com\/","name":"Mazarron Online","description":"","publisher":{"@id":"https:\/\/mazarrononline.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mazarrononline.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/mazarrononline.com\/#organization","name":"Mazarron Online","url":"https:\/\/mazarrononline.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/mazarrononline.com\/#\/schema\/logo\/image\/","url":"https:\/\/mazarrononline.com\/wp-content\/uploads\/2026\/03\/mazarrononline.com_.png","contentUrl":"https:\/\/mazarrononline.com\/wp-content\/uploads\/2026\/03\/mazarrononline.com_.png","width":891,"height":340,"caption":"Mazarron Online"},"image":{"@id":"https:\/\/mazarrononline.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mazarrononline.com\/en\/wp-json\/wp\/v2\/categories\/44","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mazarrononline.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/mazarrononline.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/mazarrononline.com\/en\/wp-json\/wp\/v2\/posts?categories=44"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}